{"id":14832,"date":"2026-05-13T10:37:30","date_gmt":"2026-05-13T13:37:30","guid":{"rendered":"https:\/\/cidadebaixaonline.com.br\/?p=14832"},"modified":"2026-05-13T10:37:31","modified_gmt":"2026-05-13T13:37:31","slug":"bahia-sedia-congresso-nacional-sobre-inovacao-e-fortalecimento-da-assistencia-farmaceutica-no-sus","status":"publish","type":"post","link":"https:\/\/cidadebaixaonline.com.br\/index.php\/2026\/05\/13\/bahia-sedia-congresso-nacional-sobre-inovacao-e-fortalecimento-da-assistencia-farmaceutica-no-sus\/","title":{"rendered":"Bahia sedia congresso nacional sobre inova\u00e7\u00e3o e fortalecimento da assist\u00eancia farmac\u00eautica no SUS"},"content":{"rendered":"<div class=\"x_elementToProof\" data-olk-copy-source=\"MessageBody\">Salvador ser\u00e1 palco, nos dias\u00a013,\u00a014 e 15 de maio, do III Congresso Baiano de Assist\u00eancia Farmac\u00eautica (COBAF.26), um dos principais eventos do pa\u00eds voltados ao debate sobre pol\u00edticas p\u00fablicas de medicamentos no \u00e2mbito do Sistema \u00danico de Sa\u00fade (SUS). A iniciativa \u00e9 promovida pela\u00a0Secretaria da Sa\u00fade do Estado da Bahia (Sesab), por meio da Superintend\u00eancia de Assist\u00eancia Farmac\u00eautica, Ci\u00eancia e Tecnologia em Sa\u00fade (Saftec), em\u00a0parceria\u00a0com a Sociedade Brasileira de Pol\u00edticas Farmac\u00eauticas (SBPFAR) e apoio do\u00a0Conselho Estadual dos Secret\u00e1rios Municipais de Sa\u00fade da Bahia (COSEMS\/BA).\u00a0A solenidade de abertura ocorrer\u00e1 no dia 14, \u00e0s 17h.<\/div>\n<div class=\"x_elementToProof\"><\/div>\n<div class=\"x_elementToProof\">Com o tema\u00a0\u201cFortalecer, integrar e qualificar: caminhos para inova\u00e7\u00e3o da Assist\u00eancia Farmac\u00eautica no SUS\u201d, o congresso, que acontece no\u00a0Hotel Deville Prime,\u00a0reunir\u00e1 cerca de 550 participantes de diferentes regi\u00f5es do pa\u00eds e\u00a0prop\u00f5e\u00a0um espa\u00e7o de articula\u00e7\u00e3o e constru\u00e7\u00e3o coletiva entre gestores, pesquisadores e profissionais que atuam na \u00e1rea, com foco na qualifica\u00e7\u00e3o da assist\u00eancia farmac\u00eautica.\u00a0Oficinas, workshops e a Mostra Bahia de Assist\u00eancia Farmac\u00eautica no SUS,\u00a0integram a programa\u00e7\u00e3o,\u00a0al\u00e9m de debates sobre temas estrat\u00e9gicos como gest\u00e3o da assist\u00eancia farmac\u00eautica, acesso a medicamentos e inova\u00e7\u00e3o.<\/div>\n<div class=\"x_elementToProof\"><\/div>\n<div class=\"x_elementToProof\">Para o superintendente da\u00a0Saftec\/SESAB,\u00a0o\u00a0congresso\u00a0refor\u00e7a o protagonismo da Bahia na constru\u00e7\u00e3o de estrat\u00e9gias para ampliar o acesso e qualificar o uso de medicamentos.\u00a0\u201cA realiza\u00e7\u00e3o do COBAF na Bahia\u00a0reafirma nosso compromisso com o fortalecimento da assist\u00eancia farmac\u00eautica no SUS, promovendo um espa\u00e7o de di\u00e1logo qualificado, troca de experi\u00eancias e constru\u00e7\u00e3o de solu\u00e7\u00f5es que impactam diretamente o cuidado \u00e0 popula\u00e7\u00e3o\u201d, destaca.<\/div>\n<div class=\"x_elementToProof\"><\/div>\n<div class=\"x_elementToProof\">Entre os destaques desta\u00a0edi\u00e7\u00e3o\u00a0est\u00e3o\u00a0a 1\u00aa Oficina Regional do Componente da Assist\u00eancia Farmac\u00eautica em Oncologia (AF-Onco), iniciativa do Minist\u00e9rio da Sa\u00fade, e\u00a0a participa\u00e7\u00e3o de\u00a0Ana\u00a0Ulbrich\u00a0\u00a0\u2014 \u00fanica representante brasileira inclu\u00edda na lista TIME100 AI 2025,\u00a0farmac\u00eautica e fundadora da NoHarm.ai<\/div>\n<div class=\"x_elementToProof\"><\/div>\n<div class=\"x_elementToProof\">Evento:\u00a0III Congresso Baiano de Assist\u00eancia Farmac\u00eautica (COBAF.26)<\/div>\n<div class=\"x_elementToProof\">Data:\u00a014 e 15 de maio de 2026<\/div>\n<div class=\"x_elementToProof\">Local:\u00a0Salvador \u2013 BA (Hotel Deville Prime)<\/div>\n<div class=\"x_elementToProof\">P\u00fablico-alvo:\u00a0gestores, pesquisadores e profissionais da assist\u00eancia farmac\u00eautica no SUS<\/div>\n<div class=\"x_elementToProof\"><\/div>\n<div class=\"x_elementToProof\">Link da Programa\u00e7\u00e3o:https:\/\/cobaf.org.br\/programacao\/<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Salvador ser\u00e1 palco, nos dias\u00a013,\u00a014 e 15 de maio, do III Congresso Baiano de Assist\u00eancia Farmac\u00eautica (COBAF.26), um dos principais eventos do pa\u00eds voltados ao debate sobre pol\u00edticas p\u00fablicas de medicamentos no \u00e2mbito do Sistema \u00danico de Sa\u00fade (SUS). A iniciativa \u00e9 promovida pela\u00a0Secretaria da Sa\u00fade do Estado da Bahia (Sesab), por meio da Superintend\u00eancia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14834,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"footnotes":""},"categories":[94],"tags":[],"class_list":["post-14832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude-2"],"_links":{"self":[{"href":"https:\/\/cidadebaixaonline.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cidadebaixaonline.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cidadebaixaonline.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cidadebaixaonline.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cidadebaixaonline.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=14832"}],"version-history":[{"count":1,"href":"https:\/\/cidadebaixaonline.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14832\/revisions"}],"predecessor-version":[{"id":14833,"href":"https:\/\/cidadebaixaonline.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14832\/revisions\/14833"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cidadebaixaonline.com.br\/index.php\/wp-json\/wp\/v2\/media\/14834"}],"wp:attachment":[{"href":"https:\/\/cidadebaixaonline.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=14832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cidadebaixaonline.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=14832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cidadebaixaonline.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=14832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}